{"id":83991,"date":"2025-06-17T11:21:31","date_gmt":"2025-06-17T09:21:31","guid":{"rendered":"https:\/\/www.englishmontessorischool.com\/?page_id=83991"},"modified":"2025-06-17T11:21:59","modified_gmt":"2025-06-17T09:21:59","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":426,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"legal-notices-es.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-83991","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso Legal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"The English Montessori School - British Montessori School in Madrid\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/englishmontessorischool\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T09:21:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.englishmontessorischool.com\/wp-content\/uploads\/sites\/121\/2024\/04\/tems-imagen-destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TemsMadrid\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Aviso Legal","og_url":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/","og_site_name":"The English Montessori School - British Montessori School in Madrid","article_publisher":"https:\/\/www.facebook.com\/englishmontessorischool\/","article_modified_time":"2025-06-17T09:21:59+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.englishmontessorischool.com\/wp-content\/uploads\/sites\/121\/2024\/04\/tems-imagen-destacada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TemsMadrid","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/","url":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/","name":"Aviso Legal","isPartOf":{"@id":"https:\/\/www.englishmontessorischool.com\/es\/#website"},"datePublished":"2025-06-17T09:21:31+00:00","dateModified":"2025-06-17T09:21:59+00:00","breadcrumb":{"@id":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.englishmontessorischool.com\/es\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.englishmontessorischool.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aviso Legal"}]},{"@type":"WebSite","@id":"https:\/\/www.englishmontessorischool.com\/es\/#website","url":"https:\/\/www.englishmontessorischool.com\/es\/","name":"The English Montessori School","description":"Discover The English Montessori School, a bilingual private school located in Madrid offering a tailor-made, holistic education for boys &amp; girls, aged 3 to 18.","publisher":{"@id":"https:\/\/www.englishmontessorischool.com\/es\/#organization"},"alternateName":"TEMS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.englishmontessorischool.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.englishmontessorischool.com\/es\/#organization","name":"The English Montessori School","alternateName":"TEMS","url":"https:\/\/www.englishmontessorischool.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.englishmontessorischool.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.englishmontessorischool.com\/wp-content\/uploads\/sites\/121\/2023\/12\/a846f8f5-6711-4e7b-a360-2c8b000685ea.png","contentUrl":"https:\/\/www.englishmontessorischool.com\/wp-content\/uploads\/sites\/121\/2023\/12\/a846f8f5-6711-4e7b-a360-2c8b000685ea.png","width":192,"height":192,"caption":"The English Montessori School"},"image":{"@id":"https:\/\/www.englishmontessorischool.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/englishmontessorischool\/","https:\/\/x.com\/TemsMadrid","https:\/\/www.instagram.com\/temsmadrid\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/pages\/83991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/users\/426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/comments?post=83991"}],"version-history":[{"count":1,"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/pages\/83991\/revisions"}],"predecessor-version":[{"id":83992,"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/pages\/83991\/revisions\/83992"}],"wp:attachment":[{"href":"https:\/\/www.englishmontessorischool.com\/es\/wp-json\/wp\/v2\/media?parent=83991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}